{"id":2571,"date":"2019-05-01T23:51:09","date_gmt":"2019-05-01T22:51:09","guid":{"rendered":"https:\/\/netzwerk-homoeopathie.info\/?p=2571"},"modified":"2019-05-01T23:51:09","modified_gmt":"2019-05-01T22:51:09","slug":"homoeopathie-zahlen-daten-fakten","status":"publish","type":"post","link":"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/","title":{"rendered":"Hom\u00f6opathie &#8211; Zahlen, Daten, Fakten"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lesedauer \/ Reading Time:<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min<\/span><\/span><div class=\"page-header\">\n<h1>Kurz erkl\u00e4rt<\/h1>\n<\/div>\n<div class=\"page-header\">\n<h2>https:\/\/www.netzwerk-homoeopathie.eu\/kurz-erklaert\/146-homoeopathie-zahlen-daten-fakten<\/h2>\n<\/div>\n<dl class=\"article-info muted\">\n<dt class=\"article-info-term\"><\/dt>\n<dd class=\"published\"><time datetime=\"2016-08-04T16:51:55+00:00\"> Ver\u00f6ffentlicht: 04. August 2016 <\/time><\/dd>\n<\/dl>\n<div class=\"pull-left item-image\"><img decoding=\"async\" src=\"https:\/\/www.netzwerk-homoeopathie.eu\/images\/Homoeopathie_Statistik.jpg\" alt=\"\" \/><\/div>\n<div>\n<p><strong>Wie viele Deutsche glauben an Hom\u00f6opathie?<\/strong><\/p>\n<p>60 Prozent der Deutschen haben schon Globuli geschluckt, sagt eine Allensbach-Studie aus dem Jahr 2014, Tendenz steigend. Dabei sind Frauen deutlich hom\u00f6opathieaffiner als M\u00e4nner: 73 Prozent der Frauen haben im Gegensatz zu 48 Prozent der M\u00e4nner schon hom\u00f6opathische Mittel genommen. \u00c4hnliche Zahlen in \u00d6sterreich: 50 Prozent der \u00d6sterreicher verwenden auch hom\u00f6opathische Mittel.<\/p>\n<p>Interessant auch bei der Allensbach-Befragung, was die Deutschen an Hom\u00f6opathika sch\u00e4tzen: dass sie keine Nebenwirkungen haben, gut vertr\u00e4glich und einfach anzuwenden sind. Stimmt nat\u00fcrlich alles. So ist das bei wirkungsloser Schein-Medizin.<\/p>\n<p>Hardcore-Hom\u00f6opathie-Gl\u00e4ubige gibt es aber weniger: Bei einer TNS Infratest-Untersuchung im Jahr 2012 sagten nur (oder immerhin) 21 Prozent der Befragten, dass sie der Aussage zustimmen, dass &#8220;alternative Heilmethoden besser bei Gesundheitsproblemen helfen als die klassische Schulmedizin&#8221;. Der Rest war unentschlossen oder anderer Meinung. Nebenbei bemerkt: Ungef\u00e4hr genauso viele Deutsche glauben, dass Sternzeichen unser Leben beeinflussen. Zufall? Oder ist es einfach so, dass rund ein Viertel der Deutschen jeden Quatsch glaubt, eine gro\u00dfe Affinit\u00e4t zu Esoterik und Geschwurbel hat?<\/p>\n<p><strong>Wie viel Umsatz wird mit Hom\u00f6opathie gemacht?<\/strong><\/p>\n<p>Hom\u00f6opathische Arzneimittel verzeichnen im Jahr 2014 in Apotheken einen <strong><em>Gesamtumsatz in H\u00f6he von 528 Millionen Euro<\/em><\/strong>. Das ist ein Zuwachs gegen\u00fcber dem Vorjahr um 9,3 Prozent. Allein die DHU (Deutsche Hom\u00f6opathie-Union) macht mit 500 Mitarbeitern einen Umsatz von 100 Millionen Euro pro Jahr.<\/p>\n<p>\u00dcbrigens steigt auch die Zahl sozialversicherungspflichtig Besch\u00e4ftigter im Bereich Heilkunde und Hom\u00f6opathie in Deutschland. Das waren im Jahr 2015 2.446 Menschen (gegen\u00fcber 1.941 im Jahr 2012).<\/p>\n<p><strong>Ist Hom\u00f6opathie kosteng\u00fcnstiger als konventionelle richtige Medizin?<\/strong><\/p>\n<p>K\u00f6nnte man meinen. Das bisschen Zucker kann doch nicht die Welt kosten. Die Statistik sagt aber das Gegenteil: Ein hom\u00f6opathisches Arzneimittel in Apotheken kostet durchschnittlich 10,86 Euro. Der Durchschnittspreis von echter Medizin bel\u00e4uft sich auf 7,75 EUR. Nebenbei erw\u00e4hnt: F\u00fcr Hom\u00f6opathika-Hersteller fallen nat\u00fcrlich keine Kosten f\u00fcr Forschung und Entwicklung an, was die Gewinnspannen im Vergleich zur oft gescholtenen &#8220;Pharmaindustrie&#8221; in ungeahnte H\u00f6hen treiben d\u00fcrfte.<\/p>\n<p>Und eine Untersuchung, bei der Daten von 44.550 Patienten ausgewertet wurden, zeigt: &#8220;Die Gesamtkosten lagen in der Hom\u00f6opathiegruppe nach 18 Monaten h\u00f6her als in der Vergleichsgruppe. Das galt f\u00fcr alle Diagnosen.&#8221; Dabei zieht hom\u00f6opathische Behandlung jede Menge Folgebehandlungen nach sich, sowohl was physische als auch psychische Belange angeht: &#8220;In den Monaten 1-3 hatten die hom\u00f6opathischen Patienten 126,2 Prozent mehr Diagnosen als die Kontrollen. Der gr\u00f6\u00dfte Unterschied zwischen den Gruppen fand sich bei den psychischen St\u00f6rungen (38.9 Prozent).&#8221;<\/p>\n<p><strong>Wie viele Krankenkassen zahlen f\u00fcr Hom\u00f6opathie?<\/strong><\/p>\n<p>Fest steht: Auf der Suche nach hom\u00f6opathiefreien Krankenkassen erlebt man sein blaues Wunder: Je nach Quelle, Z\u00e4hlung und Messung kann man sagen, dass weniger als ein Viertel, vielleicht sogar nur 4 Prozent aller Kassen auf die Bezahlung hom\u00f6opathischer Leistungen verzichten. Und fast alle Kassen zahlen neben der Hom\u00f6opathie auch f\u00fcr allen m\u00f6glichen Mumpitz: von anthroposophischer Medizin \u00fcber Ayurveda bis hin zu Eigenharntherapie.<\/p>\n<p><strong>Wie viele hom\u00f6opathiefreie Apotheken gibt es?<\/strong><\/p>\n<p>Spontan h\u00e4tte ich gesagt: keine einzige. Kaum betritt man eine Apotheke, stolpert man \u00fcber ein Regal mit Globuli f\u00fcr jede Lebenslage. Und tats\u00e4chlich hat in einer entsprechenden Internet-Datenbank bislang keine einzige der rund 20.000 deutschen Apotheken einen Eintrag gemacht. Apotheker argumentieren gerne mit der wirtschaftlichen Notwendigkeit, das anzubieten, was der Kunde nachfragt &#8211; ein Grund mehr f\u00fcr die Skeptiker-Forderung nach der Abschaffung der Apothekenpflicht f\u00fcr hom\u00f6opathische Produkte. Falls das hier \u00fcbrigens ein Apotheker liest, der explizit keine Hom\u00f6opathika verkauft: Er m\u00f6ge in den Kommentaren Bescheid sagen!<\/p>\n<p><strong>Bertreiben Hom\u00f6opathie-Anbieter Lobbyarbeit?<\/strong><\/p>\n<p>Nat\u00fcrlich. Was viele der Pharma-Industrie (nicht zu Unrecht) vorwerfen, gilt auch f\u00fcr die Anbieter von Hom\u00f6opathika. So stehen etwa der Deutsche Zentralverein hom\u00f6opathischer \u00c4rzte (DZVh\u00c4), aber auch Firmen wie die Deutsche Hom\u00f6opathie-Union (DHU), Heel, Staufen Pharma, WALA Heilmittel, Weleda und Hevert in der Kritik, weil sie Journalisten, Blogs und Websites &#8220;sponsern&#8221;, die Hom\u00f6opathie-Kritiker anprangern und einsch\u00fcchtern.<\/p>\n<p>Und nat\u00fcrlich gibt es Kooperationen und Verflechtungen, die mal mehr, mal weniger deutlich offengelegt werden. So bietet &#8211; um nur ein Beispiel zu nennen &#8211; die scheinbar der gesundheitlichen Aufkl\u00e4rung verpflichtete Carstens-Stiftung eine &#8220;Weiterbildung zum Kundenberater Hom\u00f6opathie (IHK)&#8221; an und offeriert im Rahmen dessen eine &#8220;Werksbesichtigung der DHU&#8221;, also jenes oben erw\u00e4hnten umsatzstarken Hom\u00f6opathika-Produzenten. Dem Urteil von Spiegel Online kann man sich daher nur anschlie\u00dfen: &#8220;Wo aufgekl\u00e4rtes Denken wie in Deutschland fehlt, haben Lobbyvereine wie die Carstens-Stiftung leichtes Spiel.&#8221;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Autor (und Quellen):\u00a0<a href=\"https:\/\/buggisch.wordpress.com\/2016\/08\/03\/homoeopathie-zahlen-daten-fakten\" target=\"_blank\" rel=\"noopener noreferrer\">Christian Buggisch<\/a> f\u00fcr das INH<\/p>\n<p>&nbsp;<\/p>\n<p>Foto: Christian Buggisch<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lesedauer \/ Reading Time:<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min<\/span><\/span>Kurz erkl\u00e4rt https:\/\/www.netzwerk-homoeopathie.eu\/kurz-erklaert\/146-homoeopathie-zahlen-daten-fakten Ver\u00f6ffentlicht: 04. August 2016 Wie viele Deutsche glauben an Hom\u00f6opathie? 60 Prozent der Deutschen haben schon Globuli geschluckt, sagt eine Allensbach-Studie aus dem Jahr 2014, Tendenz steigend. Dabei sind Frauen deutlich hom\u00f6opathieaffiner als M\u00e4nner: 73 Prozent der Frauen haben im Gegensatz zu 48 Prozent der M\u00e4nner schon hom\u00f6opathische Mittel genommen. \u00c4hnliche Zahlen &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Hom\u00f6opathie &#8211; Zahlen, Daten, Fakten&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[42],"tags":[],"class_list":["post-2571","post","type-post","status-publish","format-standard","hentry","category-archiv"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hom\u00f6opathie - Zahlen, Daten, Fakten - Information Network Homeopathy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hom\u00f6opathie - Zahlen, Daten, Fakten - Information Network Homeopathy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/\" \/>\n<meta property=\"og:site_name\" content=\"Information Network Homeopathy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Informationsnetzwerk-Hom%c3%b6opathie-INH-249989248680621\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-01T22:51:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.netzwerk-homoeopathie.eu\/images\/Homoeopathie_Statistik.jpg\" \/>\n<meta name=\"author\" content=\"INH-Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@homeopathy_inh\" \/>\n<meta name=\"twitter:site\" content=\"@homeopathy_inh\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"INH-Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/en\\\/homoeopathie-zahlen-daten-fakten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/en\\\/homoeopathie-zahlen-daten-fakten\\\/\"},\"author\":{\"name\":\"INH-Team\",\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/#\\\/schema\\\/person\\\/d6e4df12b1eb486f108e9a5c1bda4722\"},\"headline\":\"Hom\u00f6opathie &#8211; Zahlen, Daten, Fakten\",\"datePublished\":\"2019-05-01T22:51:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/en\\\/homoeopathie-zahlen-daten-fakten\\\/\"},\"wordCount\":772,\"publisher\":{\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/en\\\/homoeopathie-zahlen-daten-fakten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netzwerk-homoeopathie.eu\\\/images\\\/Homoeopathie_Statistik.jpg\",\"articleSection\":[\"Archive\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/en\\\/homoeopathie-zahlen-daten-fakten\\\/\",\"url\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/en\\\/homoeopathie-zahlen-daten-fakten\\\/\",\"name\":\"Hom\u00f6opathie - Zahlen, Daten, Fakten - Information Network Homeopathy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/en\\\/homoeopathie-zahlen-daten-fakten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/en\\\/homoeopathie-zahlen-daten-fakten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netzwerk-homoeopathie.eu\\\/images\\\/Homoeopathie_Statistik.jpg\",\"datePublished\":\"2019-05-01T22:51:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/en\\\/homoeopathie-zahlen-daten-fakten\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/en\\\/homoeopathie-zahlen-daten-fakten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/en\\\/homoeopathie-zahlen-daten-fakten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.netzwerk-homoeopathie.eu\\\/images\\\/Homoeopathie_Statistik.jpg\",\"contentUrl\":\"https:\\\/\\\/www.netzwerk-homoeopathie.eu\\\/images\\\/Homoeopathie_Statistik.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/en\\\/homoeopathie-zahlen-daten-fakten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hom\u00f6opathie &#8211; Zahlen, Daten, Fakten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/#website\",\"url\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/\",\"name\":\"Informations\u00adnetzwerk Hom\u00f6opathie\",\"description\":\"We explain - you have the choice\",\"publisher\":{\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/#organization\",\"name\":\"Informationsnetzwerk Hom\u00f6opathie\",\"url\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/iLogo-Schatten-1.png\",\"contentUrl\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/iLogo-Schatten-1.png\",\"width\":682,\"height\":625,\"caption\":\"Informationsnetzwerk Hom\u00f6opathie\"},\"image\":{\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Informationsnetzwerk-Hom\u00f6opathie-INH-249989248680621\\\/\",\"https:\\\/\\\/x.com\\\/homeopathy_inh\",\"https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Informationsnetzwerk_Hom\u00f6opathie\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/netzwerk-homoeopathie.info\\\/#\\\/schema\\\/person\\\/d6e4df12b1eb486f108e9a5c1bda4722\",\"name\":\"INH-Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8acfde2fe8ea3d52b24c1dc6ba88867d4bf276d7aa9c44f51c6796fb12adf627?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8acfde2fe8ea3d52b24c1dc6ba88867d4bf276d7aa9c44f51c6796fb12adf627?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8acfde2fe8ea3d52b24c1dc6ba88867d4bf276d7aa9c44f51c6796fb12adf627?s=96&d=mm&r=g\",\"caption\":\"INH-Team\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hom\u00f6opathie - Zahlen, Daten, Fakten - Information Network Homeopathy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/","og_locale":"en_US","og_type":"article","og_title":"Hom\u00f6opathie - Zahlen, Daten, Fakten - Information Network Homeopathy","og_url":"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/","og_site_name":"Information Network Homeopathy","article_publisher":"https:\/\/www.facebook.com\/Informationsnetzwerk-Hom%c3%b6opathie-INH-249989248680621\/","article_published_time":"2019-05-01T22:51:09+00:00","og_image":[{"url":"https:\/\/www.netzwerk-homoeopathie.eu\/images\/Homoeopathie_Statistik.jpg","type":"","width":"","height":""}],"author":"INH-Team","twitter_card":"summary_large_image","twitter_creator":"@homeopathy_inh","twitter_site":"@homeopathy_inh","twitter_misc":{"Written by":"INH-Team","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/#article","isPartOf":{"@id":"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/"},"author":{"name":"INH-Team","@id":"https:\/\/netzwerk-homoeopathie.info\/#\/schema\/person\/d6e4df12b1eb486f108e9a5c1bda4722"},"headline":"Hom\u00f6opathie &#8211; Zahlen, Daten, Fakten","datePublished":"2019-05-01T22:51:09+00:00","mainEntityOfPage":{"@id":"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/"},"wordCount":772,"publisher":{"@id":"https:\/\/netzwerk-homoeopathie.info\/#organization"},"image":{"@id":"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netzwerk-homoeopathie.eu\/images\/Homoeopathie_Statistik.jpg","articleSection":["Archive"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/","url":"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/","name":"Hom\u00f6opathie - Zahlen, Daten, Fakten - Information Network Homeopathy","isPartOf":{"@id":"https:\/\/netzwerk-homoeopathie.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/#primaryimage"},"image":{"@id":"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netzwerk-homoeopathie.eu\/images\/Homoeopathie_Statistik.jpg","datePublished":"2019-05-01T22:51:09+00:00","breadcrumb":{"@id":"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/#primaryimage","url":"https:\/\/www.netzwerk-homoeopathie.eu\/images\/Homoeopathie_Statistik.jpg","contentUrl":"https:\/\/www.netzwerk-homoeopathie.eu\/images\/Homoeopathie_Statistik.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/netzwerk-homoeopathie.info\/en\/homoeopathie-zahlen-daten-fakten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/netzwerk-homoeopathie.info\/"},{"@type":"ListItem","position":2,"name":"Hom\u00f6opathie &#8211; Zahlen, Daten, Fakten"}]},{"@type":"WebSite","@id":"https:\/\/netzwerk-homoeopathie.info\/#website","url":"https:\/\/netzwerk-homoeopathie.info\/","name":"Informations\u00adnetzwerk Hom\u00f6opathie","description":"We explain - you have the choice","publisher":{"@id":"https:\/\/netzwerk-homoeopathie.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/netzwerk-homoeopathie.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/netzwerk-homoeopathie.info\/#organization","name":"Informationsnetzwerk Hom\u00f6opathie","url":"https:\/\/netzwerk-homoeopathie.info\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/netzwerk-homoeopathie.info\/#\/schema\/logo\/image\/","url":"https:\/\/netzwerk-homoeopathie.info\/wp-content\/uploads\/2019\/02\/iLogo-Schatten-1.png","contentUrl":"https:\/\/netzwerk-homoeopathie.info\/wp-content\/uploads\/2019\/02\/iLogo-Schatten-1.png","width":682,"height":625,"caption":"Informationsnetzwerk Hom\u00f6opathie"},"image":{"@id":"https:\/\/netzwerk-homoeopathie.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Informationsnetzwerk-Hom\u00f6opathie-INH-249989248680621\/","https:\/\/x.com\/homeopathy_inh","https:\/\/de.wikipedia.org\/wiki\/Informationsnetzwerk_Hom\u00f6opathie"]},{"@type":"Person","@id":"https:\/\/netzwerk-homoeopathie.info\/#\/schema\/person\/d6e4df12b1eb486f108e9a5c1bda4722","name":"INH-Team","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8acfde2fe8ea3d52b24c1dc6ba88867d4bf276d7aa9c44f51c6796fb12adf627?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8acfde2fe8ea3d52b24c1dc6ba88867d4bf276d7aa9c44f51c6796fb12adf627?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8acfde2fe8ea3d52b24c1dc6ba88867d4bf276d7aa9c44f51c6796fb12adf627?s=96&d=mm&r=g","caption":"INH-Team"}}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"INH-Team","author_link":"https:\/\/netzwerk-homoeopathie.info\/en\/author\/inhudo\/"},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/netzwerk-homoeopathie.info\/en\/wp-json\/wp\/v2\/posts\/2571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/netzwerk-homoeopathie.info\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/netzwerk-homoeopathie.info\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/netzwerk-homoeopathie.info\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/netzwerk-homoeopathie.info\/en\/wp-json\/wp\/v2\/comments?post=2571"}],"version-history":[{"count":0,"href":"https:\/\/netzwerk-homoeopathie.info\/en\/wp-json\/wp\/v2\/posts\/2571\/revisions"}],"wp:attachment":[{"href":"https:\/\/netzwerk-homoeopathie.info\/en\/wp-json\/wp\/v2\/media?parent=2571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/netzwerk-homoeopathie.info\/en\/wp-json\/wp\/v2\/categories?post=2571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/netzwerk-homoeopathie.info\/en\/wp-json\/wp\/v2\/tags?post=2571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}